{"id":71,"date":"2024-04-22T14:58:00","date_gmt":"2024-04-22T14:58:00","guid":{"rendered":"https:\/\/exames.uniendo.com.br\/?p=71"},"modified":"2024-04-22T14:58:00","modified_gmt":"2024-04-22T14:58:00","slug":"balao-para-obesidade","status":"publish","type":"post","link":"https:\/\/exames.uniendo.com.br\/index.php\/2024\/04\/22\/balao-para-obesidade\/","title":{"rendered":"Bal\u00e3o para Obesidade"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>O bal\u00e3o \u00e9 um m\u00e9todo endosc\u00f3pico revers\u00edvel para perda de peso, cuja indica\u00e7\u00e3o est\u00e1 relacionada ao grau de obesidade.<\/p>\n\n\n\n<p>Utiliza uma pr\u00f3tese de silicone arredondada e \u00e9 colocado no est\u00f4mago por via endosc\u00f3pica. Instalado vazio, \u00e9 insuflado com at\u00e9 700 ml de l\u00edquido, ocupando at\u00e9 50% do est\u00f4mago. Dessa forma, permite \u00e0 pessoa comer menos, facilitando a perda de peso.<\/p>\n\n\n\n<p>A indica\u00e7\u00e3o do bal\u00e3o g\u00e1strico \u00e9 para pacientes com risco cir\u00fargico proibitivo para cirurgia ou aqueles que n\u00e3o s\u00e3o candidatos a cirurgia e que necessitam perder peso.<br>\u200b<br>Qual \u00e9 a vantagem do bal\u00e3o g\u00e1strico para obesidade?<\/p>\n\n\n\n<p>\u2192 N\u00e3o necessita de cirurgia, anestesia geral ou interna\u00e7\u00e3o hospitalar, resultando em uma recupera\u00e7\u00e3o r\u00e1pida<\/p>\n\n\n\n<p>\u2192 \u00c9 revers\u00edvel \u2014 pode ser rapidamente retirado<\/p>\n\n\n\n<p>\u2192 Precede a indica\u00e7\u00e3o de cirurgia restritiva<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"167\" src=\"https:\/\/exames.uniendo.com.br\/wp-content\/uploads\/2024\/04\/balao-gastrico-2-300x167-1.webp\" alt=\"\" class=\"wp-image-72\"\/><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O bal\u00e3o \u00e9 um m\u00e9todo endosc\u00f3pico revers\u00edvel para perda de peso, cuja indica\u00e7\u00e3o est\u00e1 relacionada ao grau de obesidade. Utiliza uma pr\u00f3tese de silicone arredondada e \u00e9 colocado no est\u00f4mago por via endosc\u00f3pica. Instalado vazio, \u00e9 insuflado com at\u00e9 700 ml de l\u00edquido, ocupando at\u00e9 50% do est\u00f4mago. Dessa forma, permite \u00e0 pessoa comer menos, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71"}],"version-history":[{"count":1,"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71\/revisions"}],"predecessor-version":[{"id":73,"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71\/revisions\/73"}],"wp:attachment":[{"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exames.uniendo.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}